{"id":2031,"date":"2011-05-10T00:00:00","date_gmt":"1999-11-30T00:00:00","guid":{"rendered":"http:\/\/www.sicdigital.com.ar\/?p=2031"},"modified":"2011-05-10T00:00:00","modified_gmt":"1999-11-30T00:00:00","slug":"empresas-dremel-presenta%c2%b3-su-herramienta-mas-potente-el-dremel-4000","status":"publish","type":"post","link":"https:\/\/sicdigital.com.ar\/sic\/empresas-dremel-presenta%c2%b3-su-herramienta-mas-potente-el-dremel-4000\/","title":{"rendered":"EMPRESAS: Dremel present\u00c3\u00b3 su herramienta m\u00c3\u00a1s potente: el Dremel 4000"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\"><img decoding=\"async\" style=\"float: left; margin: 5px; border: 1px solid black;\" src=\"http:\/\/www.presupuestosdeobra.com\/v1\/fotos\/10052011004.jpg\" alt=\"\" \/>Dremel, creadora del Minitorno, present&oacute; la nueva Dremel 4000, su multiherramienta m&aacute;s potente y precisa. Con una empu&ntilde;adura suave en las &aacute;reas de agarre para facilitar su manejo, es ideal para todo tipo de trabajos: tallado, grabado, fresado, pulido, corte, limpieza y lijado, entre muchas otras cosas.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">Una de las principales ventajas de la multiherramienta Dremel 4000 es que resulta ideal para aquellos usuarios que requieren mayor potencia por un tiempo prolongado: puede utilizarse sin problemas durante todo un d&iacute;a de trabajo, de forma ininterrumpida.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">Este innovador producto fue dise&ntilde;ado para responder a las necesidades concretas de los usuarios: facilidad de uso, comodidad, versatilidad, rendimiento. Peque&ntilde;a y pr&aacute;ctica, posee un rango de velocidad de 5.000 a 35.000 rotaciones&nbsp; por minuto, lo que ayuda al usuario a completar con mayor agilidad su trabajo. Adem&aacute;s tiene retroalimentaci&oacute;n electr&oacute;nica, que permite un constante y m&aacute;ximo desarrollo de la fuerza soportando cualquier tipo de&nbsp; exigencia.&nbsp;<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">La&nbsp;Dremel 4000, que&nbsp;dispone de un motor de alto rendimiento de&nbsp;175W, permite controlar de manera precisa y segura cualquier situaci&oacute;n, para garantizar la absoluta seguridad al trabajador. Tambi&eacute;n tiene una funci&oacute;n de bloqueo de la boquilla que evita el bloqueo accidental del eje de salida de la herramienta.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">Orientada a profesionales de joyer&iacute;a, mec&aacute;nica dental, artesanos, hobbistas, instaladores y restauradores, entre otros, la innovadora Dremel 4000 es compatible con todos los accesorios que ofrece la marca, l&iacute;der en ventas de herramientas rotativas.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">&nbsp;Acerca de Dremel<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">Desde la invenci&oacute;n del minitorno de alta velocidad hace m&aacute;s de 70 a&ntilde;os, Dremel se ha consolidado como marca l&iacute;der, proporcionando soluciones creativas para profesionales, artistas&nbsp; y hobbistas que buscan precisi&oacute;n, seguridad, durabilidad y excelente calidad, reflejada en cada una de sus creaciones.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">Con el paso de los a&ntilde;os, Dremel ampli&oacute; su gama de productos hasta consolidar un completo sistema de accesorios y complementos para herramientas. La marca hoy cuenta con un amplio portafolio de productos compuesto por:&nbsp;<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">&#8211; Minitornos Dremel Serie 300 y 400 con accesorios en diferentes presentaciones.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">&#8211; Glue Gun (Pistola Encoladora)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">&#8211; ENGRAVER (L&aacute;piz Grabador)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">&#8211; Minitorno Stylus (Inal&aacute;mbrico con tecnolog&iacute;a Ion de Litio)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">&#8211; Minitorno Dremel Digital<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">Accesorios para Tallar, Grabar, Fresar, Amolar, Afilar, Limpiar, Pulir, Cortar, Lijar, etc.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">Complementos, los cuales acompa&ntilde;an la herramienta y mejoran su desempe&ntilde;o.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\"><br \/><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><span style=\"font-size: 12px;\">Para mayor informaci&oacute;n, ingresar en <a href=\"blocked:\/\/presupuestosdeobra.comhttp\"><br \/><\/a><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\"><span style=\"font-family: arial,helvetica,sans-serif;\"><a href=\"blocked:\/\/presupuestosdeobra.comhttp\">www.dremel.com<\/a><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dremel, creadora del Minitorno, present&oacute; la nueva Dremel 4000, su multiherramienta m&aacute;s potente y precisa. Con una empu&ntilde;adura suave en las &aacute;reas de agarre para facilitar su manejo, es ideal para todo tipo de trabajos: tallado, grabado, fresado, pulido, corte, limpieza y lijado, entre muchas otras cosas. Una de las principales ventajas de la multiherramienta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[22],"tags":[42,43,44,45,47,48],"class_list":["post-2031","post","type-post","status-publish","format-standard","hentry","category-archivo","tag-arquitectura-2","tag-arqquitectura","tag-construccion","tag-diseno","tag-obra-publica-2","tag-plan-vivienda","et-doesnt-have-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts\/2031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/comments?post=2031"}],"version-history":[{"count":0,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts\/2031\/revisions"}],"wp:attachment":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/media?parent=2031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/categories?post=2031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/tags?post=2031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}