{"id":2141,"date":"2011-02-01T00:00:00","date_gmt":"2011-02-01T00:00:00","guid":{"rendered":"http:\/\/www.sicdigital.com.ar\/?p=2141"},"modified":"2011-02-01T00:00:00","modified_gmt":"2011-02-01T00:00:00","slug":"empresas-bosch-festeja-sus-125a-aniversario","status":"publish","type":"post","link":"https:\/\/sicdigital.com.ar\/sic\/empresas-bosch-festeja-sus-125a-aniversario\/","title":{"rendered":"EMPRESAS: Bosch festeja sus 125\u00c2\u00b0 aniversario"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><img loading=\"lazy\" decoding=\"async\" style=\"float: left; margin: 5px; border: 1px solid black;\" src=\"\/v1\/fotos\/01022011009.jpg\" alt=\"\" width=\"200\" height=\"85\" \/>Durante todo 2011 Bosch celebrar&aacute; un doble aniversario: los 125 a&ntilde;os del Grupo Bosch y la conmemoraci&oacute;n del cumplea&ntilde;os 150 de su fundador, Robert Bosch.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\"><span style=\"font-size: 12px;\"><span style=\"font-family: arial, helvetica, sans-serif;\">En Argentina, Bosch est&aacute; presente ininterrumpidamente desde hace m&aacute;s de 80 a&ntilde;os, cuando se estableci&oacute; el primer local de ventas en Buenos Aires. En la actualidad cuenta con m&aacute;s de 700 colaboradores en el pa&iacute;s, y sus divisiones de negocios abastecen a los m&aacute;s diversos mercados: autopartes y equipamiento original, con gran importancia en el mercado automotriz local; herramientas el&eacute;ctricas para diversas industrias y tipos de usuarios a trav&eacute;s de sus marcas Bosch, Skil y Dremel; Sistemas de Seguridad, con un amplio portafolio de productos que abarcan soluciones para la protecci&oacute;n de personas, edificios y bienes, y comunicaci&oacute;n de voz, sonido y m&uacute;sica<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\"><span style=\"font-size: 12px;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Bosch invierte a largo plazo en mercados con futuro como son las energ&iacute;as renovables y la movilidad el&eacute;ctrica. En ese sentido, casi el 50 % del presupuesto anual en Investigaci&oacute;n y Desarrollo se utiliza exclusivamente para generar productos que ayuden a ahorrar energ&iacute;a y a cuidar los recursos naturales. Esto garantiza a largo plazo la competitividad de la empresa.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\"><span style=\"font-size: 12px;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Las megatendencias como el cambio clim&aacute;tico, energ&iacute;as renovables, cambios demogr&aacute;ficos, movilidad respetuosa con el medio ambiente o el aumento de las comunicaciones a trav&eacute;s de Internet ganan cada vez m&aacute;s importancia. Bosch enfrenta los retos empresariales y ecol&oacute;gicos que resultan de ello, con su capacidad innovadora y su presencia internacional en diferentes mercados.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\"><span style=\"font-size: 12px;\"><span style=\"font-family: arial, helvetica, sans-serif;\">La empresa conmemorar&aacute; los dos aniversarios a trav&eacute;s de numerosas actividades en diferentes partes del mundo.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\"><span style=\"font-size: 12px;\"><span style=\"font-family: arial, helvetica, sans-serif;\">El Grupo Bosch tiene presencia internacional con m&aacute;s de 300 filiales y sociedades regionales en aproximadamente 60 pa&iacute;ses. Dispone de una plantilla que supera los 280.000 colaboradores en todo el mundo. La red internacional de sociedades y socios comerciales en alrededor de 150 pa&iacute;ses asegura al Grupo Bosch, tanto en el presente como a futuro, la presencia de sus productos y servicios en los mercados m&aacute;s importantes.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\"><span style=\"font-size: 12px;\"><span style=\"font-family: arial, helvetica, sans-serif;\"> El 15 de noviembre de 1886 Robert Bosch abri&oacute; su primer taller de mec&aacute;nica de precisi&oacute;n y electrotecnia en Stuttgart, Alemania, y as&iacute; sent&oacute; las bases de la empresa de tecnolog&iacute;a y servicios tal como se la conoce hoy en todo el mundo.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px;\"><span style=\"font-size: 12px;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Para m&aacute;s informaci&oacute;n, ingrese al nuevo sitio. Se trata del \u00abglobo Bosch\u00bb, un universo multimedia donde los visitantes viajar en el tiempo y descubrir tanto la historia de la empresa como el presente y futuro de las nuevas tecnolog&iacute;as.<\/span><\/span><\/span><\/p>\n<p><span style=\"font-size: 12px;\"><span lang=\"ES-AR\"><a href=\"http:\/\/www.125.bosch.com\/\" target=\"_blank\"><span style=\"font-family: arial, helvetica, sans-serif;\">www.125.bosch.com<\/span><\/a><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante todo 2011 Bosch celebrar&aacute; un doble aniversario: los 125 a&ntilde;os del Grupo Bosch y la conmemoraci&oacute;n del cumplea&ntilde;os 150 de su fundador, Robert Bosch. En Argentina, Bosch est&aacute; presente ininterrumpidamente desde hace m&aacute;s de 80 a&ntilde;os, cuando se estableci&oacute; el primer local de ventas en Buenos Aires. En la actualidad cuenta con m&aacute;s de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[22],"tags":[30,31,32],"class_list":["post-2141","post","type-post","status-publish","format-standard","hentry","category-archivo","tag-bosch","tag-herramientas-electricas","tag-nedicion-laser","et-doesnt-have-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts\/2141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/comments?post=2141"}],"version-history":[{"count":0,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts\/2141\/revisions"}],"wp:attachment":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/media?parent=2141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/categories?post=2141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/tags?post=2141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}