{"id":2235,"date":"2010-11-19T00:00:00","date_gmt":"1999-11-30T00:00:00","guid":{"rendered":"http:\/\/www.sicdigital.com.ar\/?p=2235"},"modified":"2010-11-19T00:00:00","modified_gmt":"1999-11-30T00:00:00","slug":"infovideo-multiples-ventajas-de-la-malla-redefibra","status":"publish","type":"post","link":"https:\/\/sicdigital.com.ar\/sic\/infovideo-multiples-ventajas-de-la-malla-redefibra\/","title":{"rendered":"INFOVIDEO: Multiples ventajas de la malla Redefibra."},"content":{"rendered":"<p>&nbsp;Si se aplica la malla REDEFIBRA sobre los pisos cementicios se aplica con excelentes resultados, tanto en los pisos de areas de escalera como en la ultima capa de terminaci&oacute;n de la carpeta se utilizan las mallas de 5 x 5 mm de 120gr\/m2. Respecto a los micropisos decorativos de color, tambi&eacute;n se pueden construir en terrazas y balcones con la aplicaci&oacute;n de una&nbsp; malla de 4 x 5 90gr\/m2 . Se debe cubrir toda la superficie solapando la malla 10 cm, en todos los bordes en la uni&oacute;n con muro se aplica fajas de malla de 33cm de ancho a modo de refuerzo en estas juntas.- Todas estas tecnolog&iacute;as ya demostraron sus &oacute;ptimos resultados en cada obra realizada. M&aacute;s informes t&eacute;cnicos www.redefibra.com.ar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Si se aplica la malla REDEFIBRA sobre los pisos cementicios se aplica con excelentes resultados, tanto en los pisos de areas de escalera como en la ultima capa de terminaci&oacute;n de la carpeta se utilizan las mallas de 5 x 5 mm de 120gr\/m2. Respecto a los micropisos decorativos de color, tambi&eacute;n se pueden construir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2235","post","type-post","status-publish","format-standard","hentry","category-archivo","et-doesnt-have-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts\/2235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/comments?post=2235"}],"version-history":[{"count":0,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts\/2235\/revisions"}],"wp:attachment":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/media?parent=2235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/categories?post=2235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/tags?post=2235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}