{"id":6907,"date":"2013-05-14T21:52:52","date_gmt":"2013-05-14T21:52:52","guid":{"rendered":"http:\/\/servicioinformativodelaconstruccion.com\/?p=6907"},"modified":"2013-05-14T21:52:52","modified_gmt":"2013-05-14T21:52:52","slug":"colorshop-desarrollo-su-convencion-anual","status":"publish","type":"post","link":"https:\/\/sicdigital.com.ar\/sic\/colorshop-desarrollo-su-convencion-anual\/","title":{"rendered":"Colorshop desarroll\u00f3 su Convenci\u00f3n Anual"},"content":{"rendered":"<p><a href=\"http:\/\/servicioinformativodelaconstruccion.com\/colorshop-desarrollo-su-convencion-anual\/descarga-2\/\" rel=\"attachment wp-att-6908\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-6908\" alt=\"descarga\" src=\"http:\/\/servicioinformativodelaconstruccion.com\/wp-content\/uploads\/2013\/05\/descarga.jpg\" width=\"334\" height=\"151\" \/><\/a>La cadena de pinturer\u00edas Colorshop desarroll\u00f3 su Convenci\u00f3n Anual, en la que convoc\u00f3 a los responsables de todas las franquicias del pa\u00eds para que aporten sus visiones, ejemplos y conceptos sobre el manejo de cada local.<\/p>\n<p>La misma reuni\u00f3 a los representantes de las 164 franquicias existentes en la Argentina, con proveedores y empleados de Sinteplast, que estuvieron atentos al desarrollo de todos los temas importantes para la empresa.<\/p>\n<p>Tuvo como principal orador a Ezequiel Reilly, jefe de Retail de Colorshop, qui\u00e9n afirm\u00f3: \u201cEl objetivo de Colorshop con esta convenci\u00f3n anual es reunir a su comunidad en un mismo lugar para resolver problemas comunes, determinar estrategias de mercado, regular las actividades y dar a conocer los detalles de las promociones vigentes\u201d.<\/p>\n<p>Tambi\u00e9n, cont\u00f3 con la palabra del economista Guillermo Kohan, quien desde su experiencia brind\u00f3 una charla sobre la situaci\u00f3n actual del pa\u00eds y el panorama que presenta su escenario econ\u00f3mico.<\/p>\n<p>A su vez, la agenda del encuentro, que dur\u00f3 dos d\u00edas, estuvo compuesta por presentaciones de producto, comunicaci\u00f3n y otras herramientas brindadas para los representantes de las franquicias. Para el cierre de la jornada se realizaron recorridos en la planta y locales modelos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cadena de pinturer\u00edas Colorshop desarroll\u00f3 su Convenci\u00f3n Anual, en la que convoc\u00f3 a los responsables de todas las franquicias del pa\u00eds para que aporten sus visiones, ejemplos y conceptos sobre el manejo de cada local. La misma reuni\u00f3 a los representantes de las 164 franquicias existentes en la Argentina, con proveedores y empleados de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[73],"tags":[423],"class_list":["post-6907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capacitacin","tag-colorshop","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts\/6907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/comments?post=6907"}],"version-history":[{"count":0,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/posts\/6907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/media?parent=6907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/categories?post=6907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sicdigital.com.ar\/sic\/wp-json\/wp\/v2\/tags?post=6907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}